{"id":2031,"date":"2024-04-22T08:55:30","date_gmt":"2024-04-22T08:55:30","guid":{"rendered":"https:\/\/curbelolaw.com\/?p=2031"},"modified":"2025-12-18T05:22:12","modified_gmt":"2025-12-18T10:22:12","slug":"me-quede-con-visa-de-turista-en-estados-unidos","status":"publish","type":"post","link":"https:\/\/curbelolaw.com\/es\/me-quede-con-visa-de-turista-en-estados-unidos\/","title":{"rendered":"Me qued\u00e9 con visa de turista en Estados Unidos"},"content":{"rendered":"\n<p>Si usted se pregunta: \u00bfQu\u00e9 puede pasar si me qued\u00e9 con visa de turista en Estados Unidos? Debe saber que podr\u00eda traerle serias consecuencias migratorias.<\/p>\n\n\n\n<p>Esto se debe a que la <a href=\"https:\/\/curbelolaw.com\/es\/visa-b-2-de-turistas-temporales\/\">visa B-2 de turista<\/a> es un visado temporal. Por tanto, podr\u00e1 permanecer en el pa\u00eds por unos pocos meses. Sin embargo, quedarse a vivir con esta visa conlleva el riesgo de ser deportado y enfrentar otros posibles castigos.&nbsp;<\/p>\n\n\n\n<p>Si usted desea evaluar sus posibilidades de vivir en EE. UU, no se arriesgue a quedarse ilegalmente. Ll\u00e1menos, en Curbelo Law encontrar\u00e1 la asesor\u00eda legal que necesita.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-group alignfull\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-text-color has-background has-link-color has-custom-font-size wp-element-button\" href=\"https:\/\/curbelolaw.com\/es\/contacto\/\" style=\"border-radius:999px;background-color:#D5A13A;padding-top:15px;padding-right:32px;padding-bottom:15px;padding-left:32px;font-size:21px;font-style:normal;font-weight:700;line-height:1.08\">\n\u00bfNecesita asistencia?<br>Le ayudamos con su caso\n<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">En esta p\u00e1gina<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/curbelolaw.com\/es\/me-quede-con-visa-de-turista-en-estados-unidos\/#que-ocurre-si-me-quede-con-visa-de-turista-en-2026-en-estados-unidos\" >Qu\u00e9 ocurre si me qued\u00e9 con visa de turista en 2026 en Estados Unidos<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/curbelolaw.com\/es\/me-quede-con-visa-de-turista-en-estados-unidos\/#%c2%bfcomo-quedarme-legalmente-en-estados-unidos-si-entre-con-visa-de-turista\" >\u00bfC\u00f3mo quedarme legalmente en Estados Unidos si entr\u00e9 con visa de turista?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/curbelolaw.com\/es\/me-quede-con-visa-de-turista-en-estados-unidos\/#%c2%bfrealmente-puedo-cambiar-mi-estatus-de-turista-en-estados-unidos\" >\u00bfRealmente puedo cambiar mi estatus de turista en Estados Unidos?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/curbelolaw.com\/es\/me-quede-con-visa-de-turista-en-estados-unidos\/#motivos-para-utilizar-la-visa-de-turista-en-ee-uu\" >Motivos para utilizar la visa de turista en EE. UU.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/curbelolaw.com\/es\/me-quede-con-visa-de-turista-en-estados-unidos\/#%c2%bfcomo-puedo-averiguar-el-estatus-de-solicitud-de-mi-visa-de-turista\" >\u00bfC\u00f3mo puedo averiguar el estatus de solicitud de mi visa de turista?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/curbelolaw.com\/es\/me-quede-con-visa-de-turista-en-estados-unidos\/#%c2%bfcuanto-tiempo-puedo-permanecer-en-estados-unidos-con-una-visa-de-turista\" >\u00bfCu\u00e1nto tiempo puedo permanecer en Estados Unidos con una visa de turista?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/curbelolaw.com\/es\/me-quede-con-visa-de-turista-en-estados-unidos\/#%c2%bfcomo-puedo-solicitar-una-extension-de-estadia-de-mi-visa-de-turista-en-estados-unidos\" >\u00bfC\u00f3mo puedo solicitar una extensi\u00f3n de estad\u00eda de mi visa de turista en Estados Unidos?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/curbelolaw.com\/es\/me-quede-con-visa-de-turista-en-estados-unidos\/#%c2%bfcuales-son-las-consecuencias-de-exceder-el-limite-de-tiempo-permitido-en-estados-unidos\" >\u00bfCu\u00e1les son las consecuencias de exceder el l\u00edmite de tiempo permitido en Estados Unidos?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/curbelolaw.com\/es\/me-quede-con-visa-de-turista-en-estados-unidos\/#%c2%bfque-pueden-hacer-nuestros-abogados-de-inmigracion-por-usted\" >\u00bfQu\u00e9 Pueden Hacer Nuestros Abogados De Inmigraci\u00f3n Por Usted?<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"que-ocurre-si-me-quede-con-visa-de-turista-en-2026-en-estados-unidos\"><\/span>Qu\u00e9 ocurre si me qued\u00e9 con visa de turista en 2026 en Estados Unidos<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Si usted decide quedarse en Estados Unidos con una visa de turista, podr\u00eda enfrentar consecuencias graves. Las autoridades podr\u00edan deportarlo e incluso prohibirle regresar por varios a\u00f1os.&nbsp;<\/p>\n\n\n\n<p>Todo esto es porque la visa B-2 no permite la residencia permanente legal ni trabajar en Estados Unidos.<\/p>\n\n\n\n<p>Por si fuera poco, podr\u00eda ser detenido hasta su juicio en la Corte de Inmigraci\u00f3n o hasta el d\u00eda de su deportaci\u00f3n. Esto aplica tanto para quienes tienen visa B-2 como para aquellos que ingresaron con el permiso ESTA y excedieron el per\u00edodo de 90 d\u00edas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/curbelolaw.com\/wp-content\/uploads\/2022\/01\/quedarse-con-visado-de-turista-en-estados-unidos.jpg\" alt=\"quedarse con visado de turista en estados unidos\" class=\"wp-image-3700\" srcset=\"https:\/\/curbelolaw.com\/wp-content\/uploads\/2022\/01\/quedarse-con-visado-de-turista-en-estados-unidos.jpg 800w, https:\/\/curbelolaw.com\/wp-content\/uploads\/2022\/01\/quedarse-con-visado-de-turista-en-estados-unidos-300x200.jpg 300w, https:\/\/curbelolaw.com\/wp-content\/uploads\/2022\/01\/quedarse-con-visado-de-turista-en-estados-unidos-768x512.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%c2%bfcomo-quedarme-legalmente-en-estados-unidos-si-entre-con-visa-de-turista\"><\/span>\u00bfC\u00f3mo quedarme legalmente en Estados Unidos si entr\u00e9 con visa de turista?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Tal y como mencionamos, la visa de turista es temporal, por lo que usted no podr\u00e1 quedarse en el pa\u00eds. Sin embargo, digamos que usted entr\u00f3 con la intenci\u00f3n de visitar el pa\u00eds, pero durante su estad\u00eda, se enamor\u00f3 o le llam\u00f3 la atenci\u00f3n un trabajo.<\/p>\n\n\n\n<p>De ser as\u00ed, lo primero que deber\u00e1 hacer es verificar su elegibilidad para <a href=\"https:\/\/curbelolaw.com\/es\/como-conseguir-la-green-card\/\">obtener la Tarjeta Verde<\/a> por medio del <a href=\"https:\/\/curbelolaw.com\/es\/ajuste-de-estatus\/\">ajuste de estatus<\/a>. Para ello, tendr\u00e1 que calificar a una de las siguientes categor\u00edas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/curbelolaw.com\/es\/peticion-de-familiares-a-estados-unidos\/\">Petici\u00f3n de familiares<\/a>.<\/li>\n\n\n\n<li><a href=\"https:\/\/curbelolaw.com\/es\/como-solicitar-el-asilo-politico-en-estados-unidos\/\">Asilo<\/a>.<\/li>\n\n\n\n<li>Motivos laborales.<\/li>\n\n\n\n<li>Haber sido v\u00edctima del abuso o la <a href=\"https:\/\/curbelolaw.com\/es\/que-es-la-trata-y-trafico-de-personas\/\">trata y tr\u00e1fico de personas<\/a>.<\/li>\n\n\n\n<li>Alguna categor\u00eda especial, como trabajadores religiosos (<a href=\"https:\/\/curbelolaw.com\/es\/que-es-una-visa-tipo-r\/\">visa R<\/a>) o <a href=\"https:\/\/curbelolaw.com\/es\/estatus-especial-de-inmigrante-juvenil\/\">inmigrantes juveniles especiales<\/a>.<\/li>\n<\/ul>\n\n\n\n<p class=\"has-background\" style=\"background-color:#ffecd9\">En general, si usted entra en alguna de estas clasificaciones, posiblemente pueda solicitar la residencia permanente legal.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfC\u00f3mo es el proceso para obtener la residencia si me qued\u00e9 con visa de turista en Estados Unidos?<\/h3>\n\n\n\n<p>Si cumple con lo anterior, USCIS ser\u00e1 el responsable de procesar las solicitudes de cambio de estatus de no inmigrante a inmigrante.<\/p>\n\n\n\n<p>Por tanto, para iniciar su solicitud de residencia, debe presentar los siguientes documentos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Formulario I-485.<\/li>\n\n\n\n<li>Formulario I-130 o I-140, dependiendo si es una petici\u00f3n familiar o de empleo.<\/li>\n\n\n\n<li>Solicitud I-730, si aplicar\u00e1 por refugio o asilo.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>Los requisitos para obtener la Tarjeta Verde var\u00edan seg\u00fan el motivo de la solicitud. Por otro lado, aquellos que ingresan a EE. UU. mediante el programa de exenci\u00f3n de visa, generalmente no pueden ajustar su estatus.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/curbelolaw.com\/wp-content\/uploads\/2021\/10\/abogados-de-inmigracion-en-new-jersey.jpg\" alt=\"abogados de inmigraci\u00f3n en new jersey\" class=\"wp-image-1520 size-full\" srcset=\"https:\/\/curbelolaw.com\/wp-content\/uploads\/2021\/10\/abogados-de-inmigracion-en-new-jersey.jpg 800w, https:\/\/curbelolaw.com\/wp-content\/uploads\/2021\/10\/abogados-de-inmigracion-en-new-jersey-300x200.jpg 300w, https:\/\/curbelolaw.com\/wp-content\/uploads\/2021\/10\/abogados-de-inmigracion-en-new-jersey-768x512.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-medium-font-size\">Busque la asesor\u00eda de nuestro bufete de <a href=\"https:\/\/curbelolaw.com\/es\/abogados-de-inmigracion-en-new-jersey\/\">abogados de inmigraci\u00f3n de New Jersey<\/a> para asegurarse de enviar todos los documentos requeridos y cumplir con los plazos establecidos por la ley de inmigraci\u00f3n.<\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfCu\u00e1nto tiempo tarda realizar el ajuste de estatus si me qued\u00e9 con visa de turista en Estados Unidos?<\/h3>\n\n\n\n<p>Si cambi\u00f3 su estatus de turista a alg\u00fan otro estatus migratorio v\u00e1lido para solicitar la residencia permanente legal, el tiempo para completar el ajuste de estatus variar\u00e1.&nbsp;<\/p>\n\n\n\n<p>Por lo general, lleva al menos un a\u00f1o desde el momento en que se env\u00eda la solicitud. Sin embargo, la duraci\u00f3n del proceso depende de varios factores, como si acumul\u00f3 presencia ilegal en el pa\u00eds.&nbsp;<\/p>\n\n\n\n<p>Adem\u00e1s, las solicitudes presentadas por ciudadanos americanos suelen procesarse m\u00e1s r\u00e1pido que las presentadas por los residentes permanentes legales.<\/p>\n\n\n\n<p class=\"has-background\" style=\"background-color:#ffecd9\">Es fundamental enviar la solicitud dentro del per\u00edodo de estad\u00eda autorizada en el pa\u00eds. De igual modo, mientras espera la resoluci\u00f3n, no se le permitir\u00e1 trabajar. En algunos casos, puede ser conveniente regresar al pa\u00eds de origen y solicitar el <a href=\"https:\/\/curbelolaw.com\/es\/proceso-consular\/\">procesamiento consular<\/a>.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%c2%bfrealmente-puedo-cambiar-mi-estatus-de-turista-en-estados-unidos\"><\/span>\u00bfRealmente puedo cambiar mi estatus de turista en Estados Unidos?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Es posible ajustar su estatus de una <a href=\"https:\/\/curbelolaw.com\/es\/tipo-de-visa-b-1\/\">visa B-1<\/a> o B-2 a otro tipo de visa mientras se encuentra en EE. UU. No obstante, debe cumplir con ciertos requisitos.&nbsp;<\/p>\n\n\n\n<p>Este proceso implica presentar una solicitud de cambio de estatus ante USCIS. Dicho esto, aqu\u00ed se presentan algunos puntos clave a considerar:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Prop\u00f3sito de la estad\u00eda:<\/strong> Debe demostrar que su motivo para permanecer en Estados Unidos coincide con el nuevo tipo de visa que est\u00e1 solicitando. Por ejemplo, si desea estudiar, puede solicitar un cambio a una <a href=\"https:\/\/curbelolaw.com\/es\/visa-de-estudiante-f-1\/\">visa de estudiante (F-1)<\/a>.<\/li>\n\n\n\n<li><strong>Momento:<\/strong> Debe presentar la solicitud antes de que expire su estatus actual, generalmente indicado en el registro de llegada\/salida I-94. USCIS recomienda presentar la solicitud al menos 45 d\u00edas antes de que expire su estatus actual.<\/li>\n\n\n\n<li><strong>Elegibilidad:<\/strong> No todos pueden cambiar su estatus. Por ejemplo, normalmente no puede cambiar su estatus si ingres\u00f3 a Estados Unidos bajo el ESTA.<\/li>\n\n\n\n<li><strong>Violaci\u00f3n de estatus:<\/strong> Si ha violado los t\u00e9rminos de su estatus actual, como trabajar sin autorizaci\u00f3n, no podr\u00e1 cambiar su estatus.<\/li>\n\n\n\n<li><strong>Aprobaci\u00f3n:<\/strong> Incluso si cumple con todas las condiciones y presenta una solicitud, la decisi\u00f3n final depende de USCIS.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfQu\u00e9 pasa si me cas\u00e9 con un estadounidense?<\/h3>\n\n\n\n<p>Si se ha casado recientemente con un ciudadano estadounidense o residente permanente legal, es posible que pueda solicitar la Green Card por matrimonio.&nbsp;<\/p>\n\n\n\n<p>Esto le permite permanecer en Estados Unidos y vivir con su c\u00f3nyuge. Cabe destacar que primero deber\u00e1 completar una <a href=\"https:\/\/curbelolaw.com\/es\/preguntas-para-residencia-por-matrimonio\/\">serie de preguntas para la residencia por matrimonio<\/a>.<\/p>\n\n\n\n<p class=\"has-background\" style=\"background-color:#ffecd9\">Para m\u00e1s informaci\u00f3n sobre el tema, consulte con nuestros abogados. Ellos le explicar\u00e1n todo lo que necesita saber sobre la <a href=\"https:\/\/curbelolaw.com\/es\/visa-k-1-de-prometido-de-ciudadano-americano\/\">visa K-1 de prometido<\/a>.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"motivos-para-utilizar-la-visa-de-turista-en-ee-uu\"><\/span>Motivos para utilizar la visa de turista en EE. UU.<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Algunas aplicaciones de la visa B-2 de turista en EE. UU. incluyen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Turismo.<\/li>\n\n\n\n<li>Vacaciones.<\/li>\n\n\n\n<li>Visita con amigos o familiares.<\/li>\n\n\n\n<li>Tratamiento m\u00e9dico.<\/li>\n\n\n\n<li>Participaci\u00f3n en eventos sociales organizados por organizaciones fraternales, sociales o de servicios.<\/li>\n\n\n\n<li>Participaci\u00f3n en eventos o concursos musicales, deportivos u otros similares, sin compensaci\u00f3n econ\u00f3mica.<\/li>\n\n\n\n<li>Inscripci\u00f3n en cursos de estudio recreativos cortos, no destinados a obtener cr\u00e9ditos para un t\u00edtulo acad\u00e9mico. Por ejemplo, clases de cocina durante las vacaciones.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Qu\u00e9 no hacer con la visa de turista en EE. UU.<\/h3>\n\n\n\n<p>Usted no puede hacer lo siguiente con una visa de turista en Estados Unidos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Estudiar.<\/li>\n\n\n\n<li>Conseguir empleo a largo plazo en una empresa estadounidense.<\/li>\n\n\n\n<li>Realizar actuaciones remuneradas o cualquier actividad profesional ante una audiencia que pague.<\/li>\n\n\n\n<li>Llegar como tripulante de un barco o avi\u00f3n<\/li>\n\n\n\n<li>Trabajar como prensa extranjera, en radio, cine, periodismo impreso u otros medios de informaci\u00f3n.<\/li>\n\n\n\n<li>Obtener la residencia permanente legal.<\/li>\n\n\n\n<li>Viajar con el prop\u00f3sito de dar a luz en Estados Unidos con el fin de obtener la ciudadan\u00eda estadounidense para el hijo.<\/li>\n<\/ul>\n\n\n\n<p>Los ciudadanos canadienses generalmente no requieren una visa para ingresar a Estados Unidos con prop\u00f3sitos tur\u00edsticos. Sin embargo, necesitar\u00e1n una visa adecuada si tienen planes espec\u00edficos, como estudiar, trabajar o mudarse a este pa\u00eds. Revise <a href=\"https:\/\/curbelolaw.com\/es\/visa-tn-para-mexicanos-y-canadienses\/\">la visa TN para mexicanos y canadienses<\/a>.<\/p>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/curbelolaw.com\/wp-content\/uploads\/2021\/10\/crimmigration-1.jpg\" alt=\"crimmigration\" class=\"wp-image-2062 size-full\" srcset=\"https:\/\/curbelolaw.com\/wp-content\/uploads\/2021\/10\/crimmigration-1.jpg 800w, https:\/\/curbelolaw.com\/wp-content\/uploads\/2021\/10\/crimmigration-1-300x200.jpg 300w, https:\/\/curbelolaw.com\/wp-content\/uploads\/2021\/10\/crimmigration-1-768x512.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-medium-font-size\">Es posible que un extranjero llegue a quedar detenido por inmigraci\u00f3n, especialmente si comete alg\u00fan acto <a href=\"https:\/\/curbelolaw.com\/es\/crimmigration\/\">que involucra crimmigration<\/a>. Pagar una <a href=\"https:\/\/curbelolaw.com\/es\/donde-pagar-una-fianza-de-inmigracion\/\">fianza de inmigraci\u00f3n<\/a> podr\u00eda otorgarle la libertad al infractor para posteriormente ser expulsado del pa\u00eds.<\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">\u00bfPor qu\u00e9 no puedo trabajar con visa de turista?<\/h4>\n\n\n\n<p>La visa de turista est\u00e1 destinada \u00fanicamente para fines tur\u00edsticos, por lo que no puede trabajar ni ser empleado de un empleador estadounidense.&nbsp;<\/p>\n\n\n\n<p>Por ende, si est\u00e1 interesado en trabajar en EE. UU, debe explorar otras <a href=\"https:\/\/curbelolaw.com\/es\/cuales-son-los-tipos-de-visas-americanas\/\">categor\u00edas de visas americanas<\/a>. Por ejemplo, la <a href=\"https:\/\/curbelolaw.com\/es\/cuales-son-las-visas-h-1b\/\">visa H-1B<\/a>.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%c2%bfcomo-puedo-averiguar-el-estatus-de-solicitud-de-mi-visa-de-turista\"><\/span>\u00bfC\u00f3mo puedo averiguar el estatus de solicitud de mi visa de turista?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Una vez que su solicitud de visa est\u00e1 en proceso, puede verificar el estatus del tr\u00e1mite <a href=\"https:\/\/egov.uscis.gov\/\" target=\"_blank\" rel=\"noreferrer noopener\">por Internet<\/a> o por tel\u00e9fono. Para ello, debe utilizar el n\u00famero de recibo de la solicitud.&nbsp;<\/p>\n\n\n\n<p>Para reprogramar la cita de su entrevista, le recomendamos revisar c\u00f3mo hacerlo en el <a href=\"https:\/\/travel.state.gov\/content\/travel\/en\/us-visas\/visa-information-resources\/list-of-posts.html\" target=\"_blank\" rel=\"noreferrer noopener\">portal de la embajada o consulado<\/a> donde tiene programada la cita.&nbsp;<\/p>\n\n\n\n<p>All\u00ed, seleccione la embajada o consulado correspondiente en el listado proporcionado por el Departamento de Estado y siga las instrucciones detalladas.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Pasos para conocer el estatus de una visa de turista<\/h3>\n\n\n\n<p>Las solicitudes de visa de turismo son manejadas por el Departamento de Estado de los Estados Unidos.&nbsp;<\/p>\n\n\n\n<p>Por ello, si usted ha solicitado una visa B-1 o B-2, le recomendamos utilizar el verificador de estatus de visa en l\u00ednea siguiendo estos pasos:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Seleccione la opci\u00f3n \u201cNON IMMIGRANT VISA (NIV)\u201d.<\/li>\n\n\n\n<li>Seleccione su ubicaci\u00f3n.<\/li>\n\n\n\n<li>Ingrese su n\u00famero de caso o identificaci\u00f3n.<\/li>\n\n\n\n<li>Ingrese su n\u00famero de pasaporte.<\/li>\n\n\n\n<li>Escriba las primeras 5 letras de su apellido.<\/li>\n\n\n\n<li>Complete los car\u00e1cteres que aparecen en la imagen.<\/li>\n\n\n\n<li>D\u00e9 clic en el bot\u00f3n \u201cSubmit\u201d.<\/li>\n<\/ol>\n\n\n\n<p>El Departamento de Estado no garantiza el tiempo de procesamiento de esta solicitud. Por ende, le aconsejamos ser paciente.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%c2%bfcuanto-tiempo-puedo-permanecer-en-estados-unidos-con-una-visa-de-turista\"><\/span>\u00bfCu\u00e1nto tiempo puedo permanecer en Estados Unidos con una visa de turista?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/curbelolaw.com\/wp-content\/uploads\/2022\/01\/permanecer-ilegal-con-visa-b2-de-turista.jpg\" alt=\"permanecer ilegal con visa b2 de turista\" class=\"wp-image-3701\" srcset=\"https:\/\/curbelolaw.com\/wp-content\/uploads\/2022\/01\/permanecer-ilegal-con-visa-b2-de-turista.jpg 800w, https:\/\/curbelolaw.com\/wp-content\/uploads\/2022\/01\/permanecer-ilegal-con-visa-b2-de-turista-300x200.jpg 300w, https:\/\/curbelolaw.com\/wp-content\/uploads\/2022\/01\/permanecer-ilegal-con-visa-b2-de-turista-768x512.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>Los extranjeros con visa de turista en Estados Unidos tienen un m\u00e1ximo de 180 d\u00edas o 6 meses de estad\u00eda. Eso s\u00ed, inmigraci\u00f3n puede establecer un tiempo menor.&nbsp;<\/p>\n\n\n\n<p>Si se otorgan 6 meses, se puede disfrutar la estad\u00eda aunque la entrevista consular indique menos tiempo. Es importante respetar la fecha indicada en el sello del pasaporte y obtener el Formulario I-94 para estad\u00edas prolongadas o viajes por tierra.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfPuedo quedarme m\u00e1s de 6 meses en USA con visa de visitante?<\/h3>\n\n\n\n<p>Un turista puede permanecer en Estados Unidos por m\u00e1s de 6 meses con una visa B-2, pero es necesario completar un formulario para solicitar la extensi\u00f3n de estad\u00eda.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfQu\u00e9 pasa si me quedo 5 meses en USA?<\/h3>\n\n\n\n<p>Si excede el tiempo de su visa en Estados Unidos, podr\u00eda enfrentar consecuencias severas, como la deportaci\u00f3n y la prohibici\u00f3n de reingreso. Lo m\u00e1s recomendable es cumplir con el tiempo permitido.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfQu\u00e9 Hacer Si Ya He Excedido El Tiempo De Estad\u00eda?<\/h3>\n\n\n\n<p>Si ya excedi\u00f3 el tiempo de estad\u00eda, le recomendamos seguir los siguientes pasos:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Contactar con nuestros abogados de inmigraci\u00f3n inmediatamente.<\/li>\n\n\n\n<li>Mantener la calma.<\/li>\n\n\n\n<li>Determinar la elegibilidad de un per\u00edodo de extensi\u00f3n en su visa.<\/li>\n\n\n\n<li>Cumplir todas las leyes migratorias.<\/li>\n\n\n\n<li>Ser paciente.<\/li>\n<\/ol>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%c2%bfcomo-puedo-solicitar-una-extension-de-estadia-de-mi-visa-de-turista-en-estados-unidos\"><\/span>\u00bfC\u00f3mo puedo solicitar una extensi\u00f3n de estad\u00eda de mi visa de turista en Estados Unidos?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Usted puede solicitar una extensi\u00f3n de su estad\u00eda mientras se encuentra en EE. UU. No obstante, debe ser antes de que expire su permiso de permanencia autorizado en su permiso I-94.&nbsp;<\/p>\n\n\n\n<p>Cabe destacar que no todos los individuos con una visa de turista califican para solicitar una extensi\u00f3n de estad\u00eda. De cualquier modo, usted puede <a href=\"https:\/\/www.uscis.gov\/es\/formularios\/explorar-mis-opciones\" target=\"_blank\" rel=\"noreferrer noopener\">consultar con USCIS<\/a> o con nuestros abogados para saber si puede o no puede extenderla.&nbsp;<\/p>\n\n\n\n<p>De calificar para la extensi\u00f3n, puede solicitarla por Internet o correo utilizando el Formulario I-539, siempre que pague su tarifa.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfQui\u00e9nes Califican Para Una Extensi\u00f3n De Estad\u00eda Con Visa De Turista?<\/h3>\n\n\n\n<p>Los extranjeros pueden solicitar una extensi\u00f3n de su estad\u00eda en Estados Unidos si:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Fueron admitidas legalmente en EE. UU. con una visa de no inmigrante.<\/li>\n\n\n\n<li>Su visa est\u00e1 actualmente vigente.<\/li>\n\n\n\n<li>Todav\u00eda son elegibles para su categor\u00eda de visa.<\/li>\n\n\n\n<li>No han cometido ning\u00fan delito.<\/li>\n\n\n\n<li>No han violado las condiciones de su admisi\u00f3n.<\/li>\n\n\n\n<li>Su pasaporte es v\u00e1lido y permanecer\u00e1 v\u00e1lido durante su estad\u00eda prolongada.<\/li>\n\n\n\n<li>Tienen una raz\u00f3n v\u00e1lida y leg\u00edtima para extender su estad\u00eda.<\/li>\n\n\n\n<li>Tienen planes definitivos de salir al final del per\u00edodo de extensi\u00f3n de visa propuesto.<\/li>\n\n\n\n<li>Han proporcionado pruebas v\u00e1lidas de apoyo financiero.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Consideraciones sobre el uso de la visa de turista en Estados Unidos<\/h3>\n\n\n\n<p>Si usted decide visitar Estados Unidos con una visa de turista, debe cumplir con ciertas obligaciones. Por ejemplo, tener este permiso no exime de un l\u00edmite en su estad\u00eda en el pa\u00eds.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/curbelolaw.com\/wp-content\/uploads\/2022\/01\/alargar-estadia-con-visado-de-turista.jpg\" alt=\"alargar estad\u00eda con visado de turista\" class=\"wp-image-3702\" srcset=\"https:\/\/curbelolaw.com\/wp-content\/uploads\/2022\/01\/alargar-estadia-con-visado-de-turista.jpg 800w, https:\/\/curbelolaw.com\/wp-content\/uploads\/2022\/01\/alargar-estadia-con-visado-de-turista-300x200.jpg 300w, https:\/\/curbelolaw.com\/wp-content\/uploads\/2022\/01\/alargar-estadia-con-visado-de-turista-768x513.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>La duraci\u00f3n de su estancia es determinada por un agente o inspector de migraci\u00f3n de la Oficina de Aduanas y Protecci\u00f3n Fronteriza (CBP), independientemente de la vigencia de su visa.&nbsp;<\/p>\n\n\n\n<p>Adem\u00e1s, aunque usted puede obtener una visa de turista de hasta 10 a\u00f1os para visitar EE. UU, la estad\u00eda m\u00e1xima permitida es de 180 d\u00edas o 6 meses.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%c2%bfcuales-son-las-consecuencias-de-exceder-el-limite-de-tiempo-permitido-en-estados-unidos\"><\/span>\u00bfCu\u00e1les son las consecuencias de exceder el l\u00edmite de tiempo permitido en Estados Unidos?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Si por alguna raz\u00f3n usted permanece en el pa\u00eds m\u00e1s all\u00e1 de la fecha estipulada, podr\u00eda enfrentar serias consecuencias. Estas van desde la deportaci\u00f3n hasta la cancelaci\u00f3n definitiva de su visa. Algunas de las sanciones incluyen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Si excede un d\u00eda o m\u00e1s, podr\u00eda ser considerado en \u00abpresencia ilegal\u00bb, lo que podr\u00eda limitar sus futuros tr\u00e1mites en Estados Unidos.<\/li>\n\n\n\n<li>Si supera los 180 d\u00edas, se le puede imponer una prohibici\u00f3n de ingreso al pa\u00eds por 3 a\u00f1os.<\/li>\n\n\n\n<li>Si excede un a\u00f1o, la prohibici\u00f3n de ingreso se extiende a 10 a\u00f1os.<\/li>\n<\/ul>\n\n\n\n<p>Adem\u00e1s, su visa ser\u00e1 revocada, lo que tendr\u00e1 un impacto significativo en cualquier solicitud futura para obtenerla nuevamente.<\/p>\n\n\n\n<p class=\"has-background\" style=\"background-color:#ffecd9\">En estos casos, solicitar un <a href=\"https:\/\/curbelolaw.com\/es\/como-solicitar-un-perdon-migratorio-a-estados-unidos\/\">perd\u00f3n migratorio<\/a> podr\u00eda permitirle volver a entrar al pa\u00eds sin tener que esperar a\u00f1os para ello.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfCu\u00e1ntas veces puedo visitar Estados Unidos en un mismo a\u00f1o?<\/h3>\n\n\n\n<p>No existe una regla establecida que especifique el per\u00edodo de tiempo que uno debe permanecer fuera de Estados Unidos.&nbsp;<\/p>\n\n\n\n<p>Dado que cada individuo enfrenta circunstancias \u00fanicas, no hay una respuesta exacta. Sin embargo, ciertos aspectos pueden ayudar a evitar inconvenientes, estos son:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Respetar la finalidad de la visa de turista, pues es para fines vacacionales.<\/li>\n\n\n\n<li>Mantener lazos con su pa\u00eds de origen. Por ejemplo, econ\u00f3micos, laborales, familiares, etc.<\/li>\n<\/ul>\n\n\n\n<p>Adem\u00e1s, la decisi\u00f3n de permitirle o no el ingreso al pa\u00eds recae en la discreci\u00f3n del oficial de inmigraci\u00f3n. Si determina que usted es inadmisible para ingresar a Estados Unidos, ser\u00e1 devuelto a su pa\u00eds de origen.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfCu\u00e1les podr\u00edan ser las consecuencias si el oficial tiene sospechas de que me quedar\u00e9 con la visa de turista en Estados Unidos?<\/h3>\n\n\n\n<p>El oficial de inmigraci\u00f3n tiene la facultad de decidir si se permite el ingreso al pa\u00eds. Adem\u00e1s, podr\u00eda optar por una expulsi\u00f3n inmediata o una salida voluntaria.<\/p>\n\n\n\n<p>En algunas situaciones, es posible que se requiera una segunda inspecci\u00f3n. Adem\u00e1s, al solicitar la renovaci\u00f3n de una visa de turismo, el consulado o la embajada podr\u00edan negarle la solicitud.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%c2%bfque-pueden-hacer-nuestros-abogados-de-inmigracion-por-usted\"><\/span>\u00bfQu\u00e9 Pueden Hacer Nuestros Abogados De Inmigraci\u00f3n Por Usted?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Este art\u00edculo busca ser informativo y \u00fatil con respecto a la consulta: \u201cMe qued\u00e9 con visa de turista en Estados Unidos\u201d. Ahora bien, para darle respuestas precisas es importante conocer su caso al detalle.&nbsp;<\/p>\n\n\n\n<p>Todos los asuntos legales pueden llegar a ser estresantes, complicados y dif\u00edciles, especialmente si usted lo quiere hacer por cuenta propia.&nbsp;En el bufete de abogados de Curbelo Law, la abogadas <a href=\"https:\/\/curbelolaw.com\/es\/abogada-carolina-t-curbelo\/\">Carolina T. Curbelo<\/a> puede ayudarle a atender sus necesidades legales.<\/p>\n\n\n\n<p>Ll\u00e1menos hoy mismo, env\u00edenos un E-mail y programe una cita con la oficina en Ridgewood, New Jersey.<\/p>\n\n\n\n<div class=\"wp-block-group alignfull\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-text-color has-background has-link-color has-custom-font-size wp-element-button\" href=\"https:\/\/curbelolaw.com\/es\/contacto\/\" style=\"border-radius:999px;background-color:#D5A13A;padding-top:15px;padding-right:32px;padding-bottom:15px;padding-left:32px;font-size:21px;font-style:normal;font-weight:700;line-height:1.08\">\n\u00bfNecesita asistencia?<br>Le ayudamos con su caso\n<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si usted se pregunta: \u00bfQu\u00e9 puede pasar si me qued\u00e9 con visa de turista en Estados Unidos? Debe saber que podr\u00eda traerle serias consecuencias migratorias. Esto se debe a que la visa B-2 de turista es un visado temporal. Por tanto, podr\u00e1 permanecer en el pa\u00eds por unos pocos meses. Sin embargo, quedarse a vivir [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2033,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[18],"tags":[],"class_list":["post-2031","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inmigracion","entry","has-media"],"_links":{"self":[{"href":"https:\/\/curbelolaw.com\/es\/wp-json\/wp\/v2\/posts\/2031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/curbelolaw.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/curbelolaw.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/curbelolaw.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/curbelolaw.com\/es\/wp-json\/wp\/v2\/comments?post=2031"}],"version-history":[{"count":3,"href":"https:\/\/curbelolaw.com\/es\/wp-json\/wp\/v2\/posts\/2031\/revisions"}],"predecessor-version":[{"id":10274,"href":"https:\/\/curbelolaw.com\/es\/wp-json\/wp\/v2\/posts\/2031\/revisions\/10274"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/curbelolaw.com\/es\/wp-json\/wp\/v2\/media\/2033"}],"wp:attachment":[{"href":"https:\/\/curbelolaw.com\/es\/wp-json\/wp\/v2\/media?parent=2031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/curbelolaw.com\/es\/wp-json\/wp\/v2\/categories?post=2031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/curbelolaw.com\/es\/wp-json\/wp\/v2\/tags?post=2031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}