{"id":8734,"date":"2024-06-15T10:15:57","date_gmt":"2024-06-15T10:15:57","guid":{"rendered":"https:\/\/curbelolaw.com\/?p=8734"},"modified":"2026-04-07T17:39:08","modified_gmt":"2026-04-07T21:39:08","slug":"asegurando-la-frontera","status":"publish","type":"post","link":"https:\/\/curbelolaw.com\/es\/asegurando-la-frontera\/","title":{"rendered":"Asegurando la frontera"},"content":{"rendered":"\n<p>En respuesta al significativo aumento del flujo migratorio irregular en la frontera de los Estados Unidos, la administraci\u00f3n Biden ha implementado nuevas medidas de control, asegurando procedimientos m\u00e1s estrictos para gestionar la situaci\u00f3n.<\/p>\n\n\n\n<p>Esta medida fue firmada el 3 de junio de 2024 por el presidente Joe Biden bajo las secciones 212(f) y 215(a) de la Ley de Inmigraci\u00f3n y Nacionalidad (INA).&nbsp;<\/p>\n\n\n\n<p>Esta medida determina que la entrada a los Estados Unidos de ciertos extranjeros durante circunstancias fronterizas de emergencia es perjudicial para los intereses del pa\u00eds. Tambi\u00e9n suspende y limita la entrada de los extranjeros a EE. UU.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-group alignfull\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-text-color has-background has-link-color has-custom-font-size wp-element-button\" href=\"https:\/\/curbelolaw.com\/es\/contacto\/\" style=\"border-radius:999px;background-color:#D5A13A;padding-top:15px;padding-right:32px;padding-bottom:15px;padding-left:32px;font-size:21px;font-style:normal;font-weight:700;line-height:1.08\">\n\u00bfNecesita asistencia?<br>Le ayudamos con su caso\n<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">En esta p\u00e1gina<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/curbelolaw.com\/es\/asegurando-la-frontera\/#%c2%bfpor-que-se-esta-asegurando-la-frontera-americana\" >\u00bfPor qu\u00e9 se est\u00e1 asegurando la frontera americana?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/curbelolaw.com\/es\/asegurando-la-frontera\/#cambios-importantes-en-el-proceso-migratorio\" >Cambios importantes en el proceso migratorio&nbsp;<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/curbelolaw.com\/es\/asegurando-la-frontera\/#%c2%bfasegurando-la-frontera-en-ee-uu-afectara-el-futuro-de-los-inmigrantes\" >\u00bfAsegurando la frontera en EE. UU. afectar\u00e1 el futuro de los inmigrantes?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/curbelolaw.com\/es\/asegurando-la-frontera\/#%c2%bfquienes-estaran-exentos-de-estos-cambios\" >\u00bfQui\u00e9nes estar\u00e1n exentos de estos cambios?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/curbelolaw.com\/es\/asegurando-la-frontera\/#puntos-claves-sobre-la-situacion-de-asilo-y-la-gestion-fronteriza-actual-en-los-estados-unidos\" >Puntos claves sobre la situaci\u00f3n de asilo y la gesti\u00f3n fronteriza actual en los Estados Unidos<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%c2%bfpor-que-se-esta-asegurando-la-frontera-americana\"><\/span>\u00bfPor qu\u00e9 se est\u00e1 asegurando la frontera americana?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>La frontera de los Estados Unidos se est\u00e1 asegurando debido al gran n\u00famero de inmigrantes ilegales en la frontera sur.&nbsp;<\/p>\n\n\n\n<p>Adem\u00e1s, el Departamento de Seguridad Nacional (DHS) ha implementado una regla final provisional que:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Restringe la elegibilidad para el <a href=\"https:\/\/curbelolaw.com\/es\/como-solicitar-el-asilo-politico-en-estados-unidos\/\">asilo pol\u00edtico<\/a>, y&nbsp;<\/li>\n\n\n\n<li>Aumenta las consecuencias para los inmigrantes que cruzan la frontera ilegalmente.<\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/curbelolaw.com\/wp-content\/uploads\/2024\/06\/restricciones-migratorias-de-biden.jpg\" alt=\"restricciones migratorias de biden\" class=\"wp-image-8737\" srcset=\"https:\/\/curbelolaw.com\/wp-content\/uploads\/2024\/06\/restricciones-migratorias-de-biden.jpg 800w, https:\/\/curbelolaw.com\/wp-content\/uploads\/2024\/06\/restricciones-migratorias-de-biden-300x200.jpg 300w, https:\/\/curbelolaw.com\/wp-content\/uploads\/2024\/06\/restricciones-migratorias-de-biden-768x513.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>Estas medidas temporales se mantendr\u00e1n vigentes hasta que el promedio de inmigrantes ilegales baje a menos de 1.500 por d\u00eda durante un per\u00edodo de 7 d\u00edas.&nbsp;<\/p>\n\n\n\n<p>Si el promedio vuelve a aumentar a 2.500 o m\u00e1s por d\u00eda durante estos d\u00edas, las medidas temporales se aplicar\u00e1n nuevamente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"cambios-importantes-en-el-proceso-migratorio\"><\/span>Cambios importantes en el proceso migratorio&nbsp;<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Las nuevas reglas incluyen 3 cambios clave en el procesamiento bajo las autoridades de inmigraci\u00f3n del <a href=\"https:\/\/www.law.cornell.edu\/uscode\/text\/8\" target=\"_blank\" rel=\"noreferrer noopener\">T\u00edtulo 8<\/a> durante estos per\u00edodos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Restricci\u00f3n de elegibilidad para asilo:<\/strong> Los extranjeros que crucen la frontera ilegalmente generalmente no ser\u00e1n elegibles para el asilo, salvo circunstancias excepcionalmente apremiantes.<\/li>\n\n\n\n<li><strong>Evaluaci\u00f3n de temor cre\u00edble: <\/strong>Solo aquellos sujetos a una deportaci\u00f3n acelerada ser\u00e1n evaluados por temor cre\u00edble si expresan miedo de regresar a su pa\u00eds de origen debido a la persecuci\u00f3n, tortura, o tienen la intenci\u00f3n de solicitar asilo.<\/li>\n\n\n\n<li><strong>Cumplimiento de compromisos internacionales: <\/strong>Estados Unidos seguir\u00e1 cumpliendo con sus obligaciones internacionales, pero aplicar\u00e1 un est\u00e1ndar m\u00e1s alto para quienes no califiquen para una excepci\u00f3n a la regla de elusi\u00f3n de v\u00edas legales. <\/li>\n<\/ul>\n\n\n\n<p>Estas medidas est\u00e1n destinadas a disuadir a los inmigrantes de intentar cruzar la frontera ilegalmente, lo cual es peligroso e ilegal.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/curbelolaw.com\/wp-content\/uploads\/2023\/01\/asilo-por-violencia-domestica-en-estados-unidos.jpg\" alt=\"asilo por violencia dom\u00e9stica en estados unidos\" class=\"wp-image-6452 size-full\" srcset=\"https:\/\/curbelolaw.com\/wp-content\/uploads\/2023\/01\/asilo-por-violencia-domestica-en-estados-unidos.jpg 800w, https:\/\/curbelolaw.com\/wp-content\/uploads\/2023\/01\/asilo-por-violencia-domestica-en-estados-unidos-300x200.jpg 300w, https:\/\/curbelolaw.com\/wp-content\/uploads\/2023\/01\/asilo-por-violencia-domestica-en-estados-unidos-768x512.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Si usted ha sido v\u00edctima de abusos dom\u00e9sticos, posiblemente pueda calificar para el <a href=\"https:\/\/curbelolaw.com\/es\/asilo-por-violencia-domestica-en-estados-unidos\/\">asilo por violencia dom\u00e9stica en EE. UU.<\/a>&nbsp;<\/p>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%c2%bfasegurando-la-frontera-en-ee-uu-afectara-el-futuro-de-los-inmigrantes\"><\/span>\u00bfAsegurando la frontera en EE. UU. afectar\u00e1 el futuro de los inmigrantes?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Se espera que estos cambios reduzcan significativamente la inmigraci\u00f3n ilegal en EE. UU. Es m\u00e1s, desde el 5 de junio de 2024, los procedimientos de asilo y aplicaci\u00f3n de la ley de inmigraci\u00f3n en la frontera sur de Estados Unidos son m\u00e1s rigurosos.&nbsp;<\/p>\n\n\n\n<p>Por si fuera poco, aquellos cuya entrada est\u00e9 suspendida y cruzan ilegalmente entre puertos de entrada, enfrentar\u00e1n las siguientes consecuencias:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Probablemente, no ser\u00e1n elegibles para solicitar asilo.<\/li>\n\n\n\n<li>Ser\u00e1n deportados a su pa\u00eds de origen o a un tercer pa\u00eds.<\/li>\n\n\n\n<li>Enfrentar\u00e1n al menos una prohibici\u00f3n de reingreso de 5 a\u00f1os.<\/li>\n\n\n\n<li>Podr\u00edan enfrentar posibles cargos criminales.<\/li>\n<\/ul>\n\n\n\n<p>Los inmigrantes enfrentan diversos peligros durante el viaje ilegal a los EE. UU, incluyendo la explotaci\u00f3n por parte de contrabandistas y c\u00e1rteles, as\u00ed como riesgos m\u00e9dicos graves.&nbsp;<\/p>\n\n\n\n<p>Por estos motivos, se insta a los inmigrantes a utilizar v\u00edas legales para ingresar a Estados Unidos y evitar poner en riesgo sus vidas y las de sus familias.<\/p>\n\n\n\n<p class=\"has-background\" style=\"background-color:#ffecd9\">\u00bfAlguna vez ha escuchado o le\u00eddo sobre el reloj de asilo? Descubra <a href=\"https:\/\/curbelolaw.com\/es\/que-es-el-reloj-de-asilo\/\">qu\u00e9 es el reloj de asilo<\/a> en nuestro art\u00edculo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%c2%bfquienes-estaran-exentos-de-estos-cambios\"><\/span>\u00bfQui\u00e9nes estar\u00e1n exentos de estos cambios?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Quienes estar\u00e1n exentos de estos cambios son:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Inmigrantes que utilicen un proceso adecuado para el ingreso seguro y ordenado a trav\u00e9s de un puerto de entrada, como la <a href=\"https:\/\/www.cbp.gov\/about\/mobile-apps-directory\/cbpone\" target=\"_blank\" rel=\"noreferrer noopener\">aplicaci\u00f3n m\u00f3vil CBP One<\/a>.<\/li>\n\n\n\n<li>Residentes permanentes legales.<\/li>\n\n\n\n<li><a href=\"https:\/\/curbelolaw.com\/es\/menores-inmigrantes-no-acompanados\/\">Menores inmigrantes no acompa\u00f1ados<\/a>.<\/li>\n\n\n\n<li>V\u00edctimas de la <a href=\"https:\/\/curbelolaw.com\/es\/que-es-la-trata-y-trafico-de-personas\/\">trata y tr\u00e1fico de personas<\/a>.<\/li>\n\n\n\n<li>Otros extranjeros con un <a href=\"https:\/\/curbelolaw.com\/es\/cuales-son-los-tipos-de-visas-americanas\/\">tipo de visa americana<\/a> v\u00e1lida u otro permiso legal para ingresar a los Estados Unidos.<\/li>\n<\/ul>\n\n\n\n<p>En otras palabras, estas acciones migratorias tienen el objetivo de impedir que los inmigrantes que cruzan ilegalmente la frontera sur reciban asilo.&nbsp;<\/p>\n\n\n\n<p>Por consiguiente, facilita su expulsi\u00f3n y aliviando la carga de los agentes de la Patrulla Fronteriza.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"puntos-claves-sobre-la-situacion-de-asilo-y-la-gestion-fronteriza-actual-en-los-estados-unidos\"><\/span>Puntos claves sobre la situaci\u00f3n de asilo y la gesti\u00f3n fronteriza actual en los Estados Unidos<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Actualmente, la situaci\u00f3n en la frontera sur de EE. UU. enfrenta desaf\u00edos significativos debido a una combinaci\u00f3n de pol\u00edticas restrictivas y una crisis migratoria global sin precedentes.&nbsp;<\/p>\n\n\n\n<p>A continuaci\u00f3n se presentan los puntos clave sobre las recientes medidas y propuestas relacionadas con la gesti\u00f3n migratoria y el asilo en EE. UU:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Restricciones al asilo<\/h3>\n\n\n\n<p>En los \u00faltimos a\u00f1os, se ha dificultado la solicitud de protecci\u00f3n en la frontera sur de EE. UU. debido a ciertas pol\u00edticas rigurosas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Crisis migratoria global<\/h3>\n\n\n\n<p>La inmigraci\u00f3n mundial est\u00e1 en niveles sin precedentes, con un aumento de muertes de inmigrantes debido a rutas peligrosas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Necesidad de reformas<\/h3>\n\n\n\n<p>Debido a lo mencionado previamente, el Congreso y la administraci\u00f3n Biden han mejorado todo el sistema de inmigraci\u00f3n y no solo la gesti\u00f3n fronteriza.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Nuevas acciones ejecutivas<\/h3>\n\n\n\n<p>Las recientes acciones para cerrar la frontera entre puertos de entrada buscan facilitar la expulsi\u00f3n de inmigrantes sin base legal para quedarse.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Normas provisionales <\/h3>\n\n\n\n<p>La norma final provisional del DHS\/DOJ titulada \u201cAsegurar la frontera\u201d entr\u00f3 en vigor el 5 de junio de 2024.<\/p>\n\n\n\n<p>Cabe destacar que la regla de elusi\u00f3n de v\u00edas legales fue anulada en julio de 2023, pero sigue vigente debido a apelaciones.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Programas de permanencia temporal<\/h3>\n\n\n\n<p>En vista a la dif\u00edcil situaci\u00f3n migratoria en EE. UU, se han creado programas que ofrecen un permiso de permanencia temporal para inmigrantes de ciertos pa\u00edses.&nbsp;<\/p>\n\n\n\n<p>Por ejemplo, Venezuela, Nicaragua, Hait\u00ed y Cuba, siempre y cuando cumplan con los <a href=\"https:\/\/curbelolaw.com\/es\/requisitos-para-el-parole-humanitario\/\">requisitos del parole humanitario<\/a>.<\/p>\n\n\n\n<p>Tambi\u00e9n est\u00e1 el <a href=\"https:\/\/curbelolaw.com\/es\/solicitud-del-programa-unidos-por-ucrania\/\">programa Unidos por Ucrania<\/a> que permite a los ucranianos desplazados por la guerra obtener una permanencia temporal en EE. UU. si cumplen ciertos requisitos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Curbelo Law puede asistirle en una situaci\u00f3n migratoria compleja<\/h3>\n\n\n\n<p>Puede obtener m\u00e1s informaci\u00f3n en el sitio web del <a href=\"https:\/\/www.federalregister.gov\/documents\/2024\/06\/07\/2024-12435\/securing-the-border\" target=\"_blank\" rel=\"noreferrer noopener\">Registro Federal<\/a> o contactando con nuestro bufete de <a href=\"https:\/\/curbelolaw.com\/es\/abogados-de-inmigracion-en-new-jersey\/\">abogados de inmigraci\u00f3n de New Jersey<\/a>.&nbsp;<\/p>\n\n\n\n<p>Le ayudaremos a comprender sus opciones legales, preparar su solicitud de asilo o inmigraci\u00f3n, y representarlo en procedimientos legales para asegurar que sus derechos sean protegidos.<\/p>\n\n\n\n<div class=\"wp-block-group alignfull\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-text-color has-background has-link-color has-custom-font-size wp-element-button\" href=\"https:\/\/curbelolaw.com\/es\/contacto\/\" style=\"border-radius:999px;background-color:#D5A13A;padding-top:15px;padding-right:32px;padding-bottom:15px;padding-left:32px;font-size:21px;font-style:normal;font-weight:700;line-height:1.08\">\n\u00bfNecesita asistencia?<br>Le ayudamos con su caso\n<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>En respuesta al significativo aumento del flujo migratorio irregular en la frontera de los Estados Unidos, la administraci\u00f3n Biden ha implementado nuevas medidas de control, asegurando procedimientos m\u00e1s estrictos para gestionar la situaci\u00f3n. Esta medida fue firmada el 3 de junio de 2024 por el presidente Joe Biden bajo las secciones 212(f) y 215(a) de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8736,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[28],"tags":[],"class_list":["post-8734","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-y-eventos","entry","has-media"],"_links":{"self":[{"href":"https:\/\/curbelolaw.com\/es\/wp-json\/wp\/v2\/posts\/8734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/curbelolaw.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/curbelolaw.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/curbelolaw.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/curbelolaw.com\/es\/wp-json\/wp\/v2\/comments?post=8734"}],"version-history":[{"count":3,"href":"https:\/\/curbelolaw.com\/es\/wp-json\/wp\/v2\/posts\/8734\/revisions"}],"predecessor-version":[{"id":11590,"href":"https:\/\/curbelolaw.com\/es\/wp-json\/wp\/v2\/posts\/8734\/revisions\/11590"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/curbelolaw.com\/es\/wp-json\/wp\/v2\/media\/8736"}],"wp:attachment":[{"href":"https:\/\/curbelolaw.com\/es\/wp-json\/wp\/v2\/media?parent=8734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/curbelolaw.com\/es\/wp-json\/wp\/v2\/categories?post=8734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/curbelolaw.com\/es\/wp-json\/wp\/v2\/tags?post=8734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}